{"id":3179,"date":"2023-06-30T10:17:15","date_gmt":"2023-06-30T09:17:15","guid":{"rendered":"https:\/\/fuerstenriedwest.de\/neighborhood\/"},"modified":"2026-04-27T16:30:53","modified_gmt":"2026-04-27T15:30:53","slug":"neighborhood","status":"publish","type":"page","link":"https:\/\/fuerstenriedwest.de\/en\/neighborhood\/","title":{"rendered":"Neighborhood"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"inc\/neighborhood-tpl.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3179","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quartier F\u00fcrstenried West | Neighborhood<\/title>\n<meta name=\"description\" content=\"The neighborhood program in F\u00fcrstenried West - places, offers, activities and news.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuerstenriedwest.de\/en\/neighborhood\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quartier F\u00fcrstenried West | Neighborhood\" \/>\n<meta property=\"og:description\" content=\"The neighborhood program in F\u00fcrstenried West - places, offers, activities and news.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuerstenriedwest.de\/en\/neighborhood\/\" \/>\n<meta property=\"og:site_name\" content=\"F\u00fcrstenried West\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T15:30:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuerstenriedwest.de\\\/en\\\/neighborhood\\\/\",\"url\":\"https:\\\/\\\/fuerstenriedwest.de\\\/en\\\/neighborhood\\\/\",\"name\":\"Quartier F\u00fcrstenried West | Neighborhood\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuerstenriedwest.de\\\/en\\\/#website\"},\"datePublished\":\"2023-06-30T09:17:15+00:00\",\"dateModified\":\"2026-04-27T15:30:53+00:00\",\"description\":\"The neighborhood program in F\u00fcrstenried West - places, offers, activities and news.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuerstenriedwest.de\\\/en\\\/neighborhood\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuerstenriedwest.de\\\/en\\\/neighborhood\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuerstenriedwest.de\\\/en\\\/neighborhood\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fuerstenriedwest.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neighborhood\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuerstenriedwest.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fuerstenriedwest.de\\\/en\\\/\",\"name\":\"F\u00fcrstenried West\",\"description\":\"Eine andere WordPress-Site.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuerstenriedwest.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quartier F\u00fcrstenried West | Neighborhood","description":"The neighborhood program in F\u00fcrstenried West - places, offers, activities and news.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuerstenriedwest.de\/en\/neighborhood\/","og_locale":"en_US","og_type":"article","og_title":"Quartier F\u00fcrstenried West | Neighborhood","og_description":"The neighborhood program in F\u00fcrstenried West - places, offers, activities and news.","og_url":"https:\/\/fuerstenriedwest.de\/en\/neighborhood\/","og_site_name":"F\u00fcrstenried West","article_modified_time":"2026-04-27T15:30:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fuerstenriedwest.de\/en\/neighborhood\/","url":"https:\/\/fuerstenriedwest.de\/en\/neighborhood\/","name":"Quartier F\u00fcrstenried West | Neighborhood","isPartOf":{"@id":"https:\/\/fuerstenriedwest.de\/en\/#website"},"datePublished":"2023-06-30T09:17:15+00:00","dateModified":"2026-04-27T15:30:53+00:00","description":"The neighborhood program in F\u00fcrstenried West - places, offers, activities and news.","breadcrumb":{"@id":"https:\/\/fuerstenriedwest.de\/en\/neighborhood\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuerstenriedwest.de\/en\/neighborhood\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fuerstenriedwest.de\/en\/neighborhood\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fuerstenriedwest.de\/en\/"},{"@type":"ListItem","position":2,"name":"Neighborhood"}]},{"@type":"WebSite","@id":"https:\/\/fuerstenriedwest.de\/en\/#website","url":"https:\/\/fuerstenriedwest.de\/en\/","name":"F\u00fcrstenried West","description":"Eine andere WordPress-Site.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuerstenriedwest.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/fuerstenriedwest.de\/en\/wp-json\/wp\/v2\/pages\/3179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuerstenriedwest.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fuerstenriedwest.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fuerstenriedwest.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fuerstenriedwest.de\/en\/wp-json\/wp\/v2\/comments?post=3179"}],"version-history":[{"count":96,"href":"https:\/\/fuerstenriedwest.de\/en\/wp-json\/wp\/v2\/pages\/3179\/revisions"}],"predecessor-version":[{"id":4520,"href":"https:\/\/fuerstenriedwest.de\/en\/wp-json\/wp\/v2\/pages\/3179\/revisions\/4520"}],"wp:attachment":[{"href":"https:\/\/fuerstenriedwest.de\/en\/wp-json\/wp\/v2\/media?parent=3179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}